{"id":4446,"date":"2025-12-05T18:40:17","date_gmt":"2025-12-05T23:40:17","guid":{"rendered":"https:\/\/montcascade.s2.whc.webmarketersdev.ca\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/"},"modified":"2025-12-18T17:17:09","modified_gmt":"2025-12-18T22:17:09","slug":"points-de-vente-de-nourriture-et-de-services","status":"publish","type":"page","link":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/","title":{"rendered":"Points de vente de nourriture et de services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4446\" class=\"elementor elementor-4446 elementor-2113\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56b7435 e-flex e-con-boxed e-con e-parent\" data-id=\"56b7435\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fc09e42 e-con-full e-flex e-con e-child\" data-id=\"fc09e42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6860158 e-con-full e-flex e-con e-child\" data-id=\"6860158\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d301a62 visually-hidden elementor-widget elementor-widget-heading\" data-id=\"d301a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Points de vente de nourriture et de services<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8097eb7 elementor-widget elementor-widget-heading\" data-id=\"8097eb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Nourriture et services<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04630b8 elementor-widget elementor-widget-heading\" data-id=\"04630b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">POINTS DE VENTE<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-efdad9f e-flex e-con-boxed e-con e-parent\" data-id=\"efdad9f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b807007 e-con-full e-flex e-con e-child\" data-id=\"b807007\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f5d305 elementor-absolute elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-template\" data-id=\"7f5d305\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"4366\" class=\"elementor elementor-4366 elementor-1786 elementor-1786\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23d62ffb e-con-full banner-sidebar-buttons e-flex e-con e-child\" data-id=\"23d62ffb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-3d7da494 e-con-full item e-flex e-con e-child\" data-id=\"3d7da494\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDU1NCwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t<div class=\"elementor-element elementor-element-1c57ee4 e-con-full circle e-flex e-con e-child\" data-id=\"1c57ee4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a3cf4a1 lh-0 icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4a3cf4a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"16\" viewBox=\"0 0 17 16\" fill=\"none\"><path d=\"M6.57645 0.972592C7.2656 -0.324197 9.11451 -0.324197 9.80367 0.972592L16.164 12.9295C16.313 13.2097 16.3873 13.5239 16.3796 13.8415C16.3718 14.1591 16.2824 14.4693 16.1199 14.7418C15.9573 15.0143 15.7274 15.2399 15.4523 15.3965C15.1773 15.5531 14.8665 15.6355 14.5504 15.6356H1.82974C1.51359 15.6355 1.20285 15.5531 0.927797 15.3965C0.652746 15.2399 0.422763 15.0143 0.260262 14.7418C0.0977609 14.4693 0.00828302 14.1591 0.000547954 13.8415C-0.00718711 13.5239 0.0670845 13.2097 0.216125 12.9295L6.57645 0.972592ZM8.42013 1.71557C8.39772 1.67386 8.36451 1.63902 8.32401 1.61474C8.28351 1.59045 8.23722 1.57763 8.19006 1.57763C8.14289 1.57763 8.09661 1.59045 8.05611 1.61474C8.0156 1.63902 7.98239 1.67386 7.95999 1.71557L1.59967 13.6725C1.57836 13.7125 1.56772 13.7574 1.56879 13.8027C1.56985 13.8481 1.58259 13.8924 1.60575 13.9313C1.62892 13.9703 1.66173 14.0025 1.70098 14.0249C1.74023 14.0473 1.78459 14.0592 1.82974 14.0592H14.5504C14.5955 14.0592 14.6399 14.0473 14.6791 14.0249C14.7184 14.0025 14.7512 13.9703 14.7744 13.9313C14.7975 13.8924 14.8103 13.8481 14.8113 13.8027C14.8124 13.7574 14.8018 13.7125 14.7804 13.6725L8.42013 1.71557ZM8.97438 5.9149V8.5421C8.97438 8.75114 8.89174 8.95161 8.74466 9.09942C8.59757 9.24723 8.39807 9.33027 8.19006 9.33027C7.98204 9.33027 7.78255 9.24723 7.63546 9.09942C7.48837 8.95161 7.40574 8.75114 7.40574 8.5421V5.9149C7.40574 5.70586 7.48837 5.50539 7.63546 5.35758C7.78255 5.20977 7.98204 5.12673 8.19006 5.12673C8.39807 5.12673 8.59757 5.20977 8.74466 5.35758C8.89174 5.50539 8.97438 5.70586 8.97438 5.9149ZM9.23582 11.432C9.23582 11.7107 9.12564 11.978 8.92952 12.1751C8.7334 12.3722 8.46741 12.4829 8.19006 12.4829C7.9127 12.4829 7.64671 12.3722 7.45059 12.1751C7.25447 11.978 7.1443 11.7107 7.1443 11.432C7.1443 11.1533 7.25447 10.886 7.45059 10.6889C7.64671 10.4919 7.9127 10.3811 8.19006 10.3811C8.46741 10.3811 8.7334 10.4919 8.92952 10.6889C9.12564 10.886 9.23582 11.1533 9.23582 11.432Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5518a9f elementor-absolute label elementor-widget elementor-widget-heading\" data-id=\"5518a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Alertes<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-e8e1e20 e-con-full item e-flex e-con e-child\" data-id=\"e8e1e20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDU3MSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t<div class=\"elementor-element elementor-element-bace183 e-con-full circle e-flex e-con e-child\" data-id=\"bace183\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d81a571 lh-0 icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d81a571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"19\" viewBox=\"0 0 19 19\" fill=\"none\"><path d=\"M9.2794 15.7767C9.52554 15.7767 9.76159 15.8745 9.93563 16.0486C10.1097 16.2226 10.2074 16.4586 10.2074 16.7048V17.6328C10.2074 17.879 10.1097 18.115 9.93563 18.289C9.76159 18.4631 9.52554 18.5609 9.2794 18.5609C9.03327 18.5609 8.79722 18.4631 8.62318 18.289C8.44914 18.115 8.35136 17.879 8.35136 17.6328V16.7048C8.35136 16.4586 8.44914 16.2226 8.62318 16.0486C8.79722 15.8745 9.03327 15.7767 9.2794 15.7767ZM15.1855 13.8742L15.8416 14.5304C16.0106 14.7054 16.1042 14.9398 16.1021 15.1832C16.1 15.4265 16.0024 15.6593 15.8303 15.8313C15.6582 16.0034 15.4255 16.101 15.1821 16.1031C14.9388 16.1052 14.7044 16.0117 14.5293 15.8426L13.8732 15.1865C13.7042 15.0115 13.6106 14.777 13.6127 14.5337C13.6149 14.2904 13.7125 14.0576 13.8845 13.8856C14.0566 13.7135 14.2894 13.6159 14.5327 13.6138C14.776 13.6117 15.0104 13.7052 15.1855 13.8742ZM3.37334 13.8742C3.54035 13.7078 3.76445 13.6112 4.00012 13.604C4.2358 13.5968 4.46538 13.6796 4.64223 13.8355C4.81908 13.9914 4.92995 14.2089 4.95231 14.4436C4.97467 14.6783 4.90685 14.9127 4.76262 15.0993L4.68559 15.1865L4.02946 15.8426C3.86245 16.0091 3.63835 16.1057 3.40268 16.1129C3.167 16.1201 2.93742 16.0373 2.76057 15.8814C2.58372 15.7254 2.47285 15.508 2.45049 15.2733C2.42813 15.0386 2.49595 14.8041 2.64018 14.6176L2.71721 14.5304L3.37334 13.8742ZM9.2794 3.71217C10.7562 3.71217 12.1725 4.29883 13.2168 5.34308C14.261 6.38733 14.8477 7.80364 14.8477 9.28043C14.8477 10.7572 14.261 12.1735 13.2168 13.2178C12.1725 14.262 10.7562 14.8487 9.2794 14.8487C7.80261 14.8487 6.3863 14.262 5.34205 13.2178C4.2978 12.1735 3.71114 10.7572 3.71114 9.28043C3.71114 7.80364 4.2978 6.38733 5.34205 5.34308C6.3863 4.29883 7.80261 3.71217 9.2794 3.71217ZM9.2794 5.56826C8.29487 5.56826 7.35067 5.95936 6.6545 6.65553C5.95833 7.3517 5.56723 8.2959 5.56723 9.28043C5.56723 10.265 5.95833 11.2092 6.6545 11.9053C7.35067 12.6015 8.29487 12.9926 9.2794 12.9926C10.2639 12.9926 11.2081 12.6015 11.9043 11.9053C12.6005 11.2092 12.9916 10.265 12.9916 9.28043C12.9916 8.2959 12.6005 7.3517 11.9043 6.65553C11.2081 5.95936 10.2639 5.56826 9.2794 5.56826ZM1.85506 8.35239C2.0916 8.35265 2.31911 8.44322 2.49111 8.6056C2.66311 8.76798 2.76661 8.98991 2.78048 9.22604C2.79434 9.46218 2.71751 9.69469 2.56569 9.87608C2.41387 10.0575 2.19852 10.174 1.96364 10.202L1.85506 10.2085H0.927015C0.690476 10.2082 0.462964 10.1176 0.290964 9.95526C0.118964 9.79288 0.0154586 9.57095 0.00159627 9.33482C-0.012266 9.09869 0.0645609 8.86617 0.21638 8.68478C0.368199 8.5034 0.58355 8.38682 0.818434 8.35888L0.927015 8.35239H1.85506ZM17.6318 8.35239C17.8779 8.35239 18.114 8.45016 18.288 8.62421C18.4621 8.79825 18.5598 9.0343 18.5598 9.28043C18.5598 9.52656 18.4621 9.76262 18.288 9.93666C18.114 10.1107 17.8779 10.2085 17.6318 10.2085H16.7037C16.4576 10.2085 16.2216 10.1107 16.0475 9.93666C15.8735 9.76262 15.7757 9.52656 15.7757 9.28043C15.7757 9.0343 15.8735 8.79825 16.0475 8.62421C16.2216 8.45016 16.4576 8.35239 16.7037 8.35239H17.6318ZM2.71721 2.71824C2.87701 2.55845 3.08963 2.46246 3.31517 2.44828C3.5407 2.4341 3.76367 2.5027 3.94223 2.64121L4.02946 2.71824L4.68559 3.37437C4.85203 3.54137 4.94867 3.76547 4.95586 4.00115C4.96306 4.23683 4.88028 4.46641 4.72434 4.64326C4.56839 4.82011 4.35098 4.93098 4.11626 4.95334C3.88154 4.9757 3.6471 4.90787 3.46057 4.76365L3.37334 4.68662L2.71721 4.03049C2.54323 3.85646 2.44549 3.62045 2.44549 3.37437C2.44549 3.12828 2.54323 2.89227 2.71721 2.71824ZM15.8416 2.71824C16.0156 2.89227 16.1133 3.12828 16.1133 3.37437C16.1133 3.62045 16.0156 3.85646 15.8416 4.03049L15.1855 4.68662C15.0999 4.77526 14.9975 4.84596 14.8842 4.89459C14.771 4.94323 14.6492 4.96883 14.526 4.9699C14.4028 4.97097 14.2806 4.94749 14.1665 4.90083C14.0525 4.85417 13.9488 4.78526 13.8617 4.69812C13.7746 4.61098 13.7057 4.50737 13.659 4.39331C13.6123 4.27926 13.5889 4.15706 13.5899 4.03383C13.591 3.91061 13.6166 3.78883 13.6652 3.6756C13.7139 3.56238 13.7846 3.45997 13.8732 3.37437L14.5293 2.71824C14.7034 2.54426 14.9394 2.44652 15.1855 2.44652C15.4316 2.44652 15.6676 2.54426 15.8416 2.71824ZM9.2794 0C9.52554 0 9.76159 0.0977757 9.93563 0.271818C10.1097 0.445859 10.2074 0.681911 10.2074 0.928043V1.85609C10.2074 2.10222 10.1097 2.33827 9.93563 2.51231C9.76159 2.68635 9.52554 2.78413 9.2794 2.78413C9.03327 2.78413 8.79722 2.68635 8.62318 2.51231C8.44914 2.33827 8.35136 2.10222 8.35136 1.85609V0.928043C8.35136 0.681911 8.44914 0.445859 8.62318 0.271818C8.79722 0.0977757 9.03327 0 9.2794 0Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bc8da1 elementor-absolute label elementor-widget elementor-widget-heading\" data-id=\"6bc8da1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Conditions<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-2ebd62f e-con-full item e-flex e-con e-child\" data-id=\"2ebd62f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDU1MSwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t<div class=\"elementor-element elementor-element-0fead87 e-con-full circle e-flex e-con e-child\" data-id=\"0fead87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edac359 lh-0 icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"edac359\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\"><path d=\"M8.19006 0C12.7134 0 16.3801 3.66669 16.3801 8.19006C16.3801 12.7134 12.7134 16.3801 8.19006 16.3801C3.66669 16.3801 0 12.7134 0 8.19006C0 3.66669 3.66669 0 8.19006 0ZM8.19006 1.63801C6.45235 1.63801 4.78581 2.32831 3.55706 3.55706C2.32831 4.78581 1.63801 6.45235 1.63801 8.19006C1.63801 9.92777 2.32831 11.5943 3.55706 12.8231C4.78581 14.0518 6.45235 14.7421 8.19006 14.7421C9.92777 14.7421 11.5943 14.0518 12.8231 12.8231C14.0518 11.5943 14.7421 9.92777 14.7421 8.19006C14.7421 6.45235 14.0518 4.78581 12.8231 3.55706C11.5943 2.32831 9.92777 1.63801 8.19006 1.63801ZM8.19006 3.27602C8.39066 3.27605 8.58428 3.3497 8.73418 3.483C8.88409 3.6163 8.97986 3.79998 9.00333 3.9992L9.00906 4.09503V7.85099L11.2261 10.068C11.373 10.2154 11.4583 10.4132 11.4646 10.6212C11.471 10.8292 11.3979 11.0318 11.2603 11.1878C11.1227 11.3439 10.9308 11.4418 10.7237 11.4615C10.5165 11.4812 10.3096 11.4214 10.145 11.2941L10.068 11.2261L7.61102 8.76909C7.48373 8.64169 7.40198 8.47589 7.37842 8.29735L7.37105 8.19006V4.09503C7.37105 3.87781 7.45734 3.6695 7.61093 3.5159C7.76453 3.36231 7.97284 3.27602 8.19006 3.27602Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-424afb4 elementor-absolute label elementor-widget elementor-widget-heading\" data-id=\"424afb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Heures d\u2019ouverture<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-ce1f4e5 e-con-full item e-flex e-con e-child\" data-id=\"ce1f4e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NDU1OCwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t<div class=\"elementor-element elementor-element-7bc2e52 e-con-full circle e-flex e-con e-child\" data-id=\"7bc2e52\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb13f09 lh-0 icon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"fb13f09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path d=\"M7.23757 8.17739C7.67934 8.17739 8.11119 8.04639 8.47852 7.80095C8.84584 7.55551 9.13213 7.20666 9.30119 6.79852C9.47025 6.39037 9.51448 5.94126 9.4283 5.50797C9.34211 5.07469 9.12938 4.67669 8.817 4.3643C8.50461 4.05192 8.10662 3.83919 7.67333 3.753C7.24004 3.66682 6.79093 3.71105 6.38278 3.88011C5.97464 4.04917 5.62579 4.33546 5.38035 4.70278C5.13491 5.07011 5.00391 5.50196 5.00391 5.94374C5.00391 6.53614 5.23924 7.10427 5.65813 7.52317C6.07702 7.94206 6.64516 8.17739 7.23757 8.17739ZM7.23757 5.19918C7.38482 5.19918 7.52877 5.24285 7.65122 5.32466C7.77366 5.40648 7.86909 5.52276 7.92544 5.65881C7.98179 5.79486 7.99654 5.94456 7.96781 6.08899C7.93908 6.23342 7.86817 6.36608 7.76404 6.47021C7.65991 6.57434 7.52725 6.64525 7.38282 6.67398C7.23839 6.70271 7.08869 6.68796 6.95264 6.63161C6.81659 6.57526 6.70031 6.47983 6.61849 6.35739C6.53668 6.23494 6.49301 6.09099 6.49301 5.94374C6.49301 5.74627 6.57146 5.55689 6.71109 5.41726C6.85072 5.27763 7.0401 5.19918 7.23757 5.19918ZM14.3778 12.0193C14.0142 10.8135 13.3508 9.71963 12.4494 8.84004C12.9511 7.93322 13.2076 6.91119 13.1934 5.87493C13.1792 4.83867 12.8949 3.82404 12.3686 2.93129C11.8422 2.03854 11.0921 1.29856 10.1922 0.784481C9.29235 0.270399 8.27392 0 7.23757 0C6.20121 0 5.18278 0.270399 4.28291 0.784481C3.38305 1.29856 2.63288 2.03854 2.10654 2.93129C1.5802 3.82404 1.29589 4.83867 1.28172 5.87493C1.26754 6.91119 1.52399 7.93322 2.02571 8.84004C1.11908 9.71672 0.45255 10.8114 0.0898786 12.0193C-0.00703969 12.3505 -0.0258804 12.6997 0.0348352 13.0395C0.0955507 13.3792 0.234171 13.7003 0.439817 13.9774C0.649341 14.2593 0.922361 14.4877 1.23672 14.6442C1.55108 14.8008 1.89791 14.881 2.24908 14.8783H12.2261C12.576 14.8798 12.9213 14.799 13.2343 14.6425C13.5473 14.4861 13.8191 14.2582 14.0279 13.9774C14.2335 13.7003 14.3721 13.3792 14.4328 13.0395C14.4936 12.6997 14.4747 12.3505 14.3778 12.0193ZM7.23757 1.47643C8.12111 1.47643 8.98482 1.73843 9.71947 2.22931C10.4541 2.72018 11.0267 3.41788 11.3648 4.23417C11.7029 5.05047 11.7914 5.94869 11.619 6.81526C11.4467 7.68183 11.0212 8.47783 10.3964 9.1026C9.77166 9.72736 8.97567 10.1528 8.10909 10.3252C7.24252 10.4976 6.34429 10.4091 5.528 10.071C4.71171 9.73287 4.01401 9.16028 3.52314 8.42564C3.03226 7.69099 2.77026 6.82728 2.77026 5.94374C2.77026 4.75893 3.24092 3.62266 4.0787 2.78487C4.91649 1.94709 6.05276 1.47643 7.23757 1.47643ZM12.8366 13.084C12.7665 13.1799 12.6746 13.2576 12.5684 13.3107C12.4622 13.3638 12.3448 13.3907 12.2261 13.3892H2.24908C2.13034 13.3907 2.01297 13.3638 1.90677 13.3107C1.80056 13.2576 1.70859 13.1799 1.63854 13.084C1.5716 12.9918 1.52671 12.8854 1.50735 12.7731C1.48799 12.6608 1.49466 12.5455 1.52686 12.4362C1.79413 11.5362 2.27426 10.7139 2.92662 10.0388C3.48287 10.6222 4.15176 11.0866 4.89276 11.4039C5.63377 11.7213 6.43147 11.8849 7.23757 11.8849C8.04366 11.8849 8.84136 11.7213 9.58237 11.4039C10.3234 11.0866 10.9923 10.6222 11.5485 10.0388C12.2009 10.7139 12.681 11.5362 12.9483 12.4362C12.9805 12.5455 12.9871 12.6608 12.9678 12.7731C12.9484 12.8854 12.9035 12.9918 12.8366 13.084Z\" fill=\"currentColor\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf2fda9 elementor-absolute label elementor-widget elementor-widget-heading\" data-id=\"cf2fda9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Webcam<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f84d9ab e-flex e-con-boxed e-con e-parent\" data-id=\"f84d9ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e4fe463 e-con-full e-flex e-con e-child\" data-id=\"e4fe463\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c172dfb e-flex e-con-boxed e-con e-child\" data-id=\"c172dfb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfdec6e elementor-widget elementor-widget-heading\" data-id=\"bfdec6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nourriture et services<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05ecb4e elementor-widget elementor-widget-heading\" data-id=\"05ecb4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INTRODUCTION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f321c p-last-mb-0 elementor-widget__width-initial elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"56f321c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Une belle journ\u00e9e de ski m\u00e9rite un endroit id\u00e9al pour se retrouver. Notre pavillon principal est l\u2019endroit o\u00f9 les espaces chaleureux, la bonne nourriture et les moments partag\u00e9s se rencontrent. Avec des options faciles mais incroyables de notre Grab N Go et de notre Food Truck, faites le plein et partagez les moments qui rendent la journ\u00e9e compl\u00e8te.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47f47c0 e-flex e-con-boxed e-con e-child\" data-id=\"47f47c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f28c2fe e-con-full e-flex e-con e-child\" data-id=\"f28c2fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b49ce00 elementor-widget elementor-widget-image\" data-id=\"b49ce00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"678\" height=\"486\" src=\"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO.png\" class=\"attachment-full size-full wp-image-4447\" alt=\"\" srcset=\"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO.png 678w, https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO-300x215.png 300w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc62731 e-con-full e-flex e-con e-child\" data-id=\"cc62731\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d218415 e-con-full e-flex e-con e-child\" data-id=\"d218415\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54c7569 elementor-widget elementor-widget-heading\" data-id=\"54c7569\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prenez<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ebc953 elementor-widget elementor-widget-heading\" data-id=\"1ebc953\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ET PARTEZ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8130399 p-last-mb-0 elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"8130399\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Con\u00e7u pour les journ\u00e9es en montagne, Grab N Go offre une nourriture rapide mais d\u00e9licieuse, des collations faciles et des boissons chaudes et froides. Pr\u00eat quand vous l\u2019\u00eates, pour que rien ne vous enl\u00e8ve de votre temps sur la neige.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eaafeae e-con-full e-flex e-con e-child\" data-id=\"eaafeae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e173ef1 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e173ef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ1cmwiOiJodHRwczpcL1wvbW9udGNhc2NhZGVzLmNhXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMlwvTUNfMjAyMl9NZW51X1dFQl9FTl9WRi5qcGciLCJ0eXBlIjoiaW1hZ2UifQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd00778 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"cd00778\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ1cmwiOiJodHRwczpcL1wvbW9udGNhc2NhZGVzLmNhXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMlwvTUNfMjAyMl9Ib3JhaXJlX1JlbW9ycXVlLWN1aXNpbmVfVkYtMS5qcGciLCJ0eXBlIjoiaW1hZ2UifQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Horaire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-176c9dd e-flex e-con-boxed e-con e-child\" data-id=\"176c9dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-950ada7 e-con-full e-flex e-con e-child\" data-id=\"950ada7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-02a5610 e-con-full e-flex e-con e-child\" data-id=\"02a5610\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55044b8 elementor-widget elementor-widget-heading\" data-id=\"55044b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Camions de<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-241104e elementor-widget elementor-widget-heading\" data-id=\"241104e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NOURRITURE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba9dd19 p-last-mb-0 elementor-widget-mobile_extra__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"ba9dd19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Un grand app\u00e9tit apr\u00e8s de grandes descentes ? Lorsque vous \u00eates pr\u00eat pour quelque chose de plus copieux, notre camion de nourriture livre. Savourez des repas chauds et satisfaisants con\u00e7us pour refaire le plein apr\u00e8s une journ\u00e9e compl\u00e8te sur la montagne.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70a305d e-con-full e-flex e-con e-child\" data-id=\"70a305d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed087a4 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"ed087a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ1cmwiOiJodHRwczpcL1wvbW9udGNhc2NhZGVzLmNhXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMlwvTUNfMjAyMl9NZW51X1dFQl9FTl9WRjIuanBnIiwidHlwZSI6ImltYWdlIn0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b7335c elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"7b7335c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ1cmwiOiJodHRwczpcL1wvbW9udGNhc2NhZGVzLmNhXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMlwvTUNfMjAyMl9Ib3JhaXJlX1ByZXQtYS1tYW5nZXJfVkYtMy5qcGciLCJ0eXBlIjoiaW1hZ2UifQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Horaire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5104058 e-con-full e-flex e-con e-child\" data-id=\"5104058\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98f33b6 elementor-widget elementor-widget-image\" data-id=\"98f33b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"678\" height=\"486\" src=\"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/TRUCKS.png\" class=\"attachment-full size-full wp-image-4448\" alt=\"\" srcset=\"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/TRUCKS.png 678w, https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/TRUCKS-300x215.png 300w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nourriture et services POINTS DE VENTE Nourriture et services INTRODUCTION Une belle journ\u00e9e de ski m\u00e9rite un endroit id\u00e9al pour se retrouver. Notre pavillon principal est l\u2019endroit o\u00f9 les espaces [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4353,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4446","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restauration | Station Mont Cascades<\/title>\n<meta name=\"description\" content=\"Le Mont Cascades propose des points de restauration pratiques pour les skieurs et planchistes souhaitant se ravitailler durant la journ\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restauration | Station Mont Cascades\" \/>\n<meta property=\"og:description\" content=\"Le Mont Cascades propose des points de restauration pratiques pour les skieurs et planchistes souhaitant se ravitailler durant la journ\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/\" \/>\n<meta property=\"og:site_name\" content=\"Mont Cascades\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T22:17:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"678\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/\",\"url\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/\",\"name\":\"Restauration | Station Mont Cascades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/montcascades.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/AND-GO.png\",\"datePublished\":\"2025-12-05T23:40:17+00:00\",\"dateModified\":\"2025-12-18T22:17:09+00:00\",\"description\":\"Le Mont Cascades propose des points de restauration pratiques pour les skieurs et planchistes souhaitant se ravitailler durant la journ\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/#primaryimage\",\"url\":\"https:\\\/\\\/montcascades.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/AND-GO.png\",\"contentUrl\":\"https:\\\/\\\/montcascades.ca\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/AND-GO.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-et-installations\\\/points-de-vente-de-nourriture-et-de-services\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mont Cascades &#8211; Ski\",\"item\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Services et installations\",\"item\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/ski\\\/services-and-facilities\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Points de vente de nourriture et de services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/\",\"name\":\"Mont Cascades\",\"description\":\"Mont Cascades Ski Resort; the family ski centre only 20 minutes from Ottawa.\",\"publisher\":{\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/#organization\",\"name\":\"Mont Cascades\",\"url\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/montcascades.ca\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/mont-cascades-logo.svg\",\"contentUrl\":\"https:\\\/\\\/montcascades.ca\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/mont-cascades-logo.svg\",\"width\":158,\"height\":41,\"caption\":\"Mont Cascades\"},\"image\":{\"@id\":\"https:\\\/\\\/montcascades.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restauration | Station Mont Cascades","description":"Le Mont Cascades propose des points de restauration pratiques pour les skieurs et planchistes souhaitant se ravitailler durant la journ\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/","og_locale":"fr_FR","og_type":"article","og_title":"Restauration | Station Mont Cascades","og_description":"Le Mont Cascades propose des points de restauration pratiques pour les skieurs et planchistes souhaitant se ravitailler durant la journ\u00e9e.","og_url":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/","og_site_name":"Mont Cascades","article_modified_time":"2025-12-18T22:17:09+00:00","og_image":[{"width":678,"height":486,"url":"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/","url":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/","name":"Restauration | Station Mont Cascades","isPartOf":{"@id":"https:\/\/montcascades.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/#primaryimage"},"image":{"@id":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/#primaryimage"},"thumbnailUrl":"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO.png","datePublished":"2025-12-05T23:40:17+00:00","dateModified":"2025-12-18T22:17:09+00:00","description":"Le Mont Cascades propose des points de restauration pratiques pour les skieurs et planchistes souhaitant se ravitailler durant la journ\u00e9e.","breadcrumb":{"@id":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/#primaryimage","url":"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO.png","contentUrl":"https:\/\/montcascades.ca\/wp-content\/uploads\/2025\/12\/AND-GO.png"},{"@type":"BreadcrumbList","@id":"https:\/\/montcascades.ca\/fr\/ski\/services-et-installations\/points-de-vente-de-nourriture-et-de-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/montcascades.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Mont Cascades &#8211; Ski","item":"https:\/\/montcascades.ca\/fr\/ski\/"},{"@type":"ListItem","position":3,"name":"Services et installations","item":"https:\/\/montcascades.ca\/fr\/ski\/services-and-facilities\/"},{"@type":"ListItem","position":4,"name":"Points de vente de nourriture et de services"}]},{"@type":"WebSite","@id":"https:\/\/montcascades.ca\/fr\/#website","url":"https:\/\/montcascades.ca\/fr\/","name":"Mont Cascades","description":"Mont Cascades Ski Resort; the family ski centre only 20 minutes from Ottawa.","publisher":{"@id":"https:\/\/montcascades.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montcascades.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/montcascades.ca\/fr\/#organization","name":"Mont Cascades","url":"https:\/\/montcascades.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/montcascades.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/montcascades.ca\/wp-content\/uploads\/2024\/12\/mont-cascades-logo.svg","contentUrl":"https:\/\/montcascades.ca\/wp-content\/uploads\/2024\/12\/mont-cascades-logo.svg","width":158,"height":41,"caption":"Mont Cascades"},"image":{"@id":"https:\/\/montcascades.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/pages\/4446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/comments?post=4446"}],"version-history":[{"count":1,"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/pages\/4446\/revisions"}],"predecessor-version":[{"id":4451,"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/pages\/4446\/revisions\/4451"}],"up":[{"embeddable":true,"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/pages\/4353"}],"wp:attachment":[{"href":"https:\/\/montcascades.ca\/fr\/wp-json\/wp\/v2\/media?parent=4446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}